{"id":2906,"date":"2025-02-25T06:14:36","date_gmt":"2025-02-25T05:14:36","guid":{"rendered":"https:\/\/radio.descargalatina.cl\/latina\/?p=2906"},"modified":"2025-02-25T06:14:37","modified_gmt":"2025-02-25T05:14:37","slug":"myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025","status":"publish","type":"post","link":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/","title":{"rendered":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Myriam Hern\u00e1ndez<\/strong>&nbsp;hizo su esperado regreso al&nbsp;<strong>Festival de Vi\u00f1a del Mar 2025<\/strong>, emocionando a m\u00e1s de&nbsp;<strong>15 mil personas<\/strong>&nbsp;en la&nbsp;<strong>Quinta Vergara<\/strong>&nbsp;tras&nbsp;<strong>23 a\u00f1os de ausencia<\/strong>. Con una introducci\u00f3n cargada de recuerdos, que incluy\u00f3 im\u00e1genes de sus participaciones previas como cantante y animadora, la artista inici\u00f3 su show con el cl\u00e1sico&nbsp;<strong>\u201cEl hombre que yo amo\u201d<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>S\u00f3lo vine a agradecerles<\/strong>\u201d, dijo visiblemente emocionada la cantante, antes de continuar con una serie de&nbsp;<strong>\u00e9xitos rom\u00e1nticos<\/strong>&nbsp;como&nbsp;<strong>\u201cResc\u00e1tame\u201d<\/strong>, coreado con pasi\u00f3n por el p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los momentos m\u00e1s memorables de la noche fue cuando los&nbsp;<strong>Power Peralta<\/strong>&nbsp;subieron al escenario para acompa\u00f1arla con un&nbsp;<strong>sensual baile<\/strong>, justo antes de interpretar&nbsp;<strong>\u201cLe\u00f1a y fuego\u201d<\/strong>, poniendo a&nbsp;<strong>bailar a toda la Quinta Vergara<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3mo era de esperarse, en medio de aplausos y algarab\u00eda del p\u00fablico, Myriam Hern\u00e1ndez recibi\u00f3 la gaviota de plata, premio que emocion\u00f3 hasta las l\u00e1grimas a la int\u00e9rprete nacional, continuando su presentaci\u00f3n, mientras que la gente exige se le entregue la ansiada gaviota de oro, que bien merecida se la tiene por todos esos \u00e9xitos que hacen vibrar a Chile y toda Latinoam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.epicentrochile.com\/2025\/02\/24\/deslumbrante-myriam-hernandez-emociona-y-hace-historia-en-vina-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">seguir leyendo Fuente: EpicentroChile.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cS\u00f3lo vine a agradecerles\u201d, dijo visiblemente emocionada la cantante, antes de continuar con una serie de \u00e9xitos rom\u00e1nticos como \u201cResc\u00e1tame\u201d, coreado con pasi\u00f3n por el p\u00fablico.<\/p>\n","protected":false},"author":2,"featured_media":2907,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[63,65,64,62],"class_list":["post-2906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-festival-de-vina-2025","tag-gaviota-de-platino","tag-myriam-hernandez","tag-vina-2025"],"featured_image_src":{"landsacpe":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg",640,404,false],"list":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1-463x348.jpg",463,348,true],"medium":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1-300x189.jpg",300,189,true],"full":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg",640,404,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025\" \/>\n<meta property=\"og:description\" content=\"\u201cS\u00f3lo vine a agradecerles\u201d, dijo visiblemente emocionada la cantante, antes de continuar con una serie de \u00e9xitos rom\u00e1nticos como \u201cResc\u00e1tame\u201d, coreado con pasi\u00f3n por el p\u00fablico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Descargalatina.cl 2025\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-25T05:14:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T05:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa Descargalatina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa Descargalatina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/\"},\"author\":{\"name\":\"Prensa Descargalatina\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/48eca3ea5888d0846cff6936dbd29162\"},\"headline\":\"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025\",\"datePublished\":\"2025-02-25T05:14:36+00:00\",\"dateModified\":\"2025-02-25T05:14:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\"},\"image\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/myriam-gaviota-platino-640x404-1.jpg\",\"keywords\":[\"festival de vi\u00f1a 2025\",\"gaviota de platino\",\"myriam hernandez\",\"vi\u00f1a 2025\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/\",\"name\":\"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/myriam-gaviota-platino-640x404-1.jpg\",\"datePublished\":\"2025-02-25T05:14:36+00:00\",\"dateModified\":\"2025-02-25T05:14:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/myriam-gaviota-platino-640x404-1.jpg\",\"contentUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/myriam-gaviota-platino-640x404-1.jpg\",\"width\":640,\"height\":404},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/02\\\/25\\\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#website\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/\",\"name\":\"Descargalatina.cl 2025\",\"description\":\"el portal radio de m\u00fasica latina en Chile.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\",\"name\":\"jonnmerino@gmail.com\",\"logo\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/48eca3ea5888d0846cff6936dbd29162\",\"name\":\"Prensa Descargalatina\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/author\\\/contactocreaideas-cl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025","og_description":"\u201cS\u00f3lo vine a agradecerles\u201d, dijo visiblemente emocionada la cantante, antes de continuar con una serie de \u00e9xitos rom\u00e1nticos como \u201cResc\u00e1tame\u201d, coreado con pasi\u00f3n por el p\u00fablico.","og_url":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/","og_site_name":"Descargalatina.cl 2025","article_published_time":"2025-02-25T05:14:36+00:00","article_modified_time":"2025-02-25T05:14:37+00:00","og_image":[{"width":640,"height":404,"url":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg","type":"image\/jpeg"}],"author":"Prensa Descargalatina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Prensa Descargalatina","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#article","isPartOf":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/"},"author":{"name":"Prensa Descargalatina","@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/48eca3ea5888d0846cff6936dbd29162"},"headline":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025","datePublished":"2025-02-25T05:14:36+00:00","dateModified":"2025-02-25T05:14:37+00:00","mainEntityOfPage":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143"},"image":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg","keywords":["festival de vi\u00f1a 2025","gaviota de platino","myriam hernandez","vi\u00f1a 2025"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/","url":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/","name":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025 - Descargalatina.cl 2025","isPartOf":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#primaryimage"},"image":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg","datePublished":"2025-02-25T05:14:36+00:00","dateModified":"2025-02-25T05:14:37+00:00","breadcrumb":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#primaryimage","url":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg","contentUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/02\/myriam-gaviota-platino-640x404-1.jpg","width":640,"height":404},{"@type":"BreadcrumbList","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/02\/25\/myriam-hernandez-recibe-gaviota-de-platino-en-vina-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/radio.descargalatina.cl\/latina\/"},{"@type":"ListItem","position":2,"name":"Myriam Hern\u00e1ndez recibe gaviota de platino en Vi\u00f1a 2025"}]},{"@type":"WebSite","@id":"https:\/\/radio.descargalatina.cl\/latina\/#website","url":"https:\/\/radio.descargalatina.cl\/latina\/","name":"Descargalatina.cl 2025","description":"el portal radio de m\u00fasica latina en Chile.","publisher":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radio.descargalatina.cl\/latina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143","name":"jonnmerino@gmail.com","logo":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/radio.descargalatina.cl\/latina"]},{"@type":"Person","@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/48eca3ea5888d0846cff6936dbd29162","name":"Prensa Descargalatina","url":"https:\/\/radio.descargalatina.cl\/latina\/author\/contactocreaideas-cl\/"}]}},"_links":{"self":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/2906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/comments?post=2906"}],"version-history":[{"count":1,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/2906\/revisions"}],"predecessor-version":[{"id":2908,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/2906\/revisions\/2908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/media\/2907"}],"wp:attachment":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/media?parent=2906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/categories?post=2906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/tags?post=2906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}