{"id":3000,"date":"2025-03-22T18:23:48","date_gmt":"2025-03-22T17:23:48","guid":{"rendered":"https:\/\/radio.descargalatina.cl\/latina\/?p=3000"},"modified":"2025-03-24T05:33:07","modified_gmt":"2025-03-24T04:33:07","slug":"mi-trayectoria-jerry-rivera-en-chile","status":"publish","type":"post","link":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/","title":{"rendered":"\u00abMI TRAYECTORIA\u00bb Jerry Rivera en Chile"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una noche de salsa rom\u00e1ntica con \u00abEl Ni\u00f1o de la Salsa\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una jornada que parti\u00f3 a eso de las 19.00 hrs citados para acreditar prensa en el recinto poco a poco fueron llegando lo asistentes para primero disfrutar de la apertura del telonero <a href=\"https:\/\/www.facebook.com\/lycanlavoz\" target=\"_blank\" rel=\"noreferrer noopener\">Rousvel Henriquez<\/a>&nbsp;artista, cantante autodidacta venezolano, quien entreg\u00f3 un amplio repertorio para dar inicio y presentaci\u00f3n al artista principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerardo Rivera Rodr\u00edguez mas conocido como <strong>Jerry Rivera<\/strong>, el ni\u00f1o de la salsa poco antes de las 22.00 hrs. inicia su show con un audiovisual recorrido por su trayectoria y el tema <strong>\u00abDIME TU\u00bb<\/strong> entre luces, efectos y bellas bailarinas hizo que sus fans corearan cada tema, buenos mixes entre los mas reconocidos, <strong>\u00abCara de Ni\u00f1o\u00bb<\/strong> , <strong>\u00abEse\u00bb<\/strong> , <strong>\u00abQue hay de Malo\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3035\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-1024x1024.jpg\" alt=\"Algunas fotos de la noche del Jueves.\" class=\"wp-image-3035\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR24-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3034\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-1024x1024.jpg\" alt=\"\" class=\"wp-image-3034\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR23-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3031\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-1024x1024.jpg\" alt=\"\" class=\"wp-image-3031\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR20-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3026\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-1024x1024.jpg\" alt=\"\" class=\"wp-image-3026\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR15-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3027\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-1024x1024.jpg\" alt=\"\" class=\"wp-image-3027\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR16-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3029\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-1024x1024.jpg\" alt=\"\" class=\"wp-image-3029\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR18-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3030\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-1024x1024.jpg\" alt=\"\" class=\"wp-image-3030\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR19-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3021\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-1024x1024.jpg\" alt=\"\" class=\"wp-image-3021\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR10-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3022\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-1024x1024.jpg\" alt=\"\" class=\"wp-image-3022\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR13-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3024\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-1024x1024.jpg\" alt=\"\" class=\"wp-image-3024\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR11-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3025\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-1024x1024.jpg\" alt=\"\" class=\"wp-image-3025\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR14-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3016\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-1024x1024.jpg\" alt=\"\" class=\"wp-image-3016\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR4-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3017\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-1024x1024.jpg\" alt=\"\" class=\"wp-image-3017\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR6-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3020\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-1024x1024.jpg\" alt=\"\" class=\"wp-image-3020\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR8-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3013\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-1024x1024.jpg\" alt=\"\" class=\"wp-image-3013\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR3-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"3015\" src=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-1024x1024.jpg\" alt=\"\" class=\"wp-image-3015\" srcset=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-1024x1024.jpg 1024w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-768x768.jpg 768w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-640x640.jpg 640w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-400x400.jpg 400w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-560x560.jpg 560w, https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/JR2-367x367.jpg 367w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n<div class=\"porto-carousel owl-carousel has-ccols has-ccols-spacing ccols-xl-6 ccols-lg-4 ccols-md-3 ccols-sm-2 ccols-1 stage-margin wpb_custom_2875a395f368a73d7b98ee439d15fd5d\" data-plugin-options=\"{&quot;themeConfig&quot;:true,&quot;stagePadding&quot;:40,&quot;margin&quot;:10,&quot;autoplay&quot;:false,&quot;mouseDrag&quot;:true,&quot;touchDrag&quot;:true,&quot;autoplayTimeout&quot;:5000,&quot;autoplayHoverPause&quot;:false,&quot;items&quot;:6,&quot;xl&quot;:6,&quot;lg&quot;:4,&quot;md&quot;:3,&quot;sm&quot;:2,&quot;xs&quot;:1,&quot;nav&quot;:false,&quot;dots&quot;:false,&quot;animateIn&quot;:&quot;&quot;,&quot;animateOut&quot;:&quot;&quot;,&quot;loop&quot;:false,&quot;center&quot;:false,&quot;video&quot;:false,&quot;lazyLoad&quot;:false,&quot;fullscreen&quot;:false}\"><\/div>\n\n\n<p class=\"wp-block-paragraph\">Fotograf\u00edas Angello Mu\u00f1oz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un Show intenso, sin pausas pocas palabras y mucha m\u00fasica, salvo algunos problemas de sonido que fueron evidentes con instrucciones en vivo por parte del artista fue un tremendo y emocionante evento, un repertorio del cual muchas de las fans a mi alrededor emocionadas gritaban a coro, exactamente a la hora del Show el artista instruye \u00absuban sus brazos, ya ver\u00e1n porque\u00bb y con esto presenta su tema <strong>\u00abAmores como El Nuestro\u00bb<\/strong>  para terminar una noche de Salsa Rom\u00e1ntica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una noche de Salsa rom\u00e1ntica con El Ni\u00f1o de la Salsa, Jerry Rivera y su tour \u00abMI TRAYECTORIA\u00bb el pasado jueves 20 en Chile.<\/p>\n","protected":false},"author":2,"featured_media":3002,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10,72],"tags":[78,75,52,77,68],"class_list":["post-3000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-noticias","category-salsa-en-chile","tag-cara-de-nino","tag-jerry-rivera","tag-salsa","tag-salsa-en-chile","tag-salsa-internacional"],"featured_image_src":{"landsacpe":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera-1140x445.jpg",1140,445,true],"list":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera-463x348.jpg",463,348,true],"medium":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera-300x121.jpg",300,121,true],"full":["https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg",1920,774,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;MI TRAYECTORIA&quot; Jerry Rivera en Chile - Descargalatina.cl 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;MI TRAYECTORIA&quot; Jerry Rivera en Chile - Descargalatina.cl 2025\" \/>\n<meta property=\"og:description\" content=\"Una noche de Salsa rom\u00e1ntica con El Ni\u00f1o de la Salsa, Jerry Rivera y su tour &quot;MI TRAYECTORIA&quot; el pasado jueves 20 en Chile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Descargalatina.cl 2025\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-22T17:23:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T04:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa Descargalatina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa Descargalatina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/\"},\"author\":{\"name\":\"Prensa Descargalatina\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/48eca3ea5888d0846cff6936dbd29162\"},\"headline\":\"\u00abMI TRAYECTORIA\u00bb Jerry Rivera en Chile\",\"datePublished\":\"2025-03-22T17:23:48+00:00\",\"dateModified\":\"2025-03-24T04:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/\"},\"wordCount\":222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\"},\"image\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jerry-rivera.jpg\",\"keywords\":[\"cara de ni\u00f1o\",\"jerry rivera\",\"salsa\",\"salsa en chile\",\"salsa internacional\"],\"articleSection\":[\"Nacionales\",\"Noticias\",\"Salsa en Chile\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/\",\"name\":\"\\\"MI TRAYECTORIA\\\" Jerry Rivera en Chile - Descargalatina.cl 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jerry-rivera.jpg\",\"datePublished\":\"2025-03-22T17:23:48+00:00\",\"dateModified\":\"2025-03-24T04:33:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jerry-rivera.jpg\",\"contentUrl\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jerry-rivera.jpg\",\"width\":1920,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/2025\\\/03\\\/22\\\/mi-trayectoria-jerry-rivera-en-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMI TRAYECTORIA\u00bb Jerry Rivera en Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#website\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/\",\"name\":\"Descargalatina.cl 2025\",\"description\":\"el portal radio de m\u00fasica latina en Chile.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/e137cb21d845248fafe225b18e5ea143\",\"name\":\"jonnmerino@gmail.com\",\"logo\":{\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/#\\\/schema\\\/person\\\/48eca3ea5888d0846cff6936dbd29162\",\"name\":\"Prensa Descargalatina\",\"url\":\"https:\\\/\\\/radio.descargalatina.cl\\\/latina\\\/author\\\/contactocreaideas-cl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"MI TRAYECTORIA\" Jerry Rivera en Chile - Descargalatina.cl 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/","og_locale":"es_ES","og_type":"article","og_title":"\"MI TRAYECTORIA\" Jerry Rivera en Chile - Descargalatina.cl 2025","og_description":"Una noche de Salsa rom\u00e1ntica con El Ni\u00f1o de la Salsa, Jerry Rivera y su tour \"MI TRAYECTORIA\" el pasado jueves 20 en Chile.","og_url":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/","og_site_name":"Descargalatina.cl 2025","article_published_time":"2025-03-22T17:23:48+00:00","article_modified_time":"2025-03-24T04:33:07+00:00","og_image":[{"width":1920,"height":774,"url":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg","type":"image\/jpeg"}],"author":"Prensa Descargalatina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Prensa Descargalatina","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#article","isPartOf":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/"},"author":{"name":"Prensa Descargalatina","@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/48eca3ea5888d0846cff6936dbd29162"},"headline":"\u00abMI TRAYECTORIA\u00bb Jerry Rivera en Chile","datePublished":"2025-03-22T17:23:48+00:00","dateModified":"2025-03-24T04:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/"},"wordCount":222,"commentCount":0,"publisher":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143"},"image":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg","keywords":["cara de ni\u00f1o","jerry rivera","salsa","salsa en chile","salsa internacional"],"articleSection":["Nacionales","Noticias","Salsa en Chile"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/","url":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/","name":"\"MI TRAYECTORIA\" Jerry Rivera en Chile - Descargalatina.cl 2025","isPartOf":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#primaryimage"},"image":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg","datePublished":"2025-03-22T17:23:48+00:00","dateModified":"2025-03-24T04:33:07+00:00","breadcrumb":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#primaryimage","url":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg","contentUrl":"https:\/\/radio.descargalatina.cl\/latina\/wp-content\/uploads\/2025\/03\/jerry-rivera.jpg","width":1920,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/radio.descargalatina.cl\/latina\/2025\/03\/22\/mi-trayectoria-jerry-rivera-en-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/radio.descargalatina.cl\/latina\/"},{"@type":"ListItem","position":2,"name":"\u00abMI TRAYECTORIA\u00bb Jerry Rivera en Chile"}]},{"@type":"WebSite","@id":"https:\/\/radio.descargalatina.cl\/latina\/#website","url":"https:\/\/radio.descargalatina.cl\/latina\/","name":"Descargalatina.cl 2025","description":"el portal radio de m\u00fasica latina en Chile.","publisher":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radio.descargalatina.cl\/latina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/e137cb21d845248fafe225b18e5ea143","name":"jonnmerino@gmail.com","logo":{"@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/radio.descargalatina.cl\/latina"]},{"@type":"Person","@id":"https:\/\/radio.descargalatina.cl\/latina\/#\/schema\/person\/48eca3ea5888d0846cff6936dbd29162","name":"Prensa Descargalatina","url":"https:\/\/radio.descargalatina.cl\/latina\/author\/contactocreaideas-cl\/"}]}},"_links":{"self":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/3000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/comments?post=3000"}],"version-history":[{"count":5,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/3000\/revisions"}],"predecessor-version":[{"id":3038,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/posts\/3000\/revisions\/3038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/media\/3002"}],"wp:attachment":[{"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/media?parent=3000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/categories?post=3000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio.descargalatina.cl\/latina\/wp-json\/wp\/v2\/tags?post=3000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}